
{"id":157641,"date":"2026-05-29T12:16:53","date_gmt":"2026-05-29T10:16:53","guid":{"rendered":"https:\/\/ms-contentfactory.srv.vocento.in\/contentfactorylocal\/?p=157641"},"modified":"2026-05-29T12:21:50","modified_gmt":"2026-05-29T10:21:50","slug":"la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador","status":"publish","type":"post","link":"\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/","title":{"rendered":"La inversi\u00f3n m\u00e1s sofisticada en Wall Street, al alcance del peque\u00f1o ahorrador"},"content":{"rendered":"<p>[vc_row][vc_column]\n    <div class='bloque'>\n        <a class='open-btn close-nav quees' href='#'>\n            <span class=''>Foro Silverway<\/span>\n        <\/a>\n        <h1>\n        <strong>La inversi\u00f3n m\u00e1s sofisticada en Wall Street, al alcance del peque\u00f1o ahorrador<\/strong>\n        <p>Pedro Escudero, uno de los mejores gestores de Estados Unidos, present\u00f3 en Bilbao su firma de gesti\u00f3n de activos Silverway AM<\/p>\n    <\/h1>\n    <\/figure><figure class='imgprincipal'><img src='\/content-local\/wp-content\/uploads\/sites\/10\/2026\/05\/silverway-portada.jpg'><\/figure><\/div>[\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-1-1 tablet-col-1-1&#8243;]<div class='firmaRRSS '>\n       <div class='info'><address class='firmaAutor' data-autor='Luis M. D\u00edez'> Luis M. D\u00edez<\/address><time class='publicacion'>\n         29 mayo, 2026 - 12:16<\/time><\/div>\n           <div class='compartir'><p>Compartir<\/p><ul>\n                <li class='facebook'>\n                            <a href='https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/elcorreo.com\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/' class='bcl-compartir-fb' data-voc-vtm-id='compartirrrss' data-voc-vtm-info='facebook' target='_blank' title='Compartelo en Facebook' rel='nofollow'>\n                        <i class='facebook'><\/i>\n                    <\/a>\n                <\/li><li class='twitter'>\n                    <a href='https:\/\/twitter.com\/intent\/tweet?text=https:\/\/elcorreo.com\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/' class='bcl-compartir-tw twitter' data-voc-vtm-id='compartirrrss' data-voc-vtm-info='twitter' target='_blank' title='Compartelo en Twitter' rel='nofollow'>\n                        <i class='twitter'><\/i>\n                    <\/a>\n                <\/li><li class='whatsapp'>\n                    <a href='whatsapp:\/\/send?text=https:\/\/elcorreo.com\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/' data-voc-vtm-id='compartirrrss' data-voc-vtm-info='whatsapp' class='whatsapp' target='_blank' title='Compartelo en whatsapp' rel='nofollow'>\n                        <i class='whatsapp'><\/i>\n                    <\/a>\n                <\/li>\n    \n    <\/ul><\/div><\/div>[\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-10-12 tablet-col-1-1&#8243;]<p class=\"parrafocount\">En un mundo sometido a tensiones geopol\u00edticas diarias que ejercen su influencia en<strong> mercados financieros<\/strong> en los que resulta complicado no solo precedir su comportamiento, sino separar el grano de la paja, conviene ponerse en manos de un buen gestor para que los ahorros generen riqueza y no quebraderos de cabeza.<\/p><p class='parrafocount'><p class='parrafocount'>Si hablamos de la \u00e9lite inversora, Estados Unidos representa la excelencia, la NBA a la que aspiran a jugar los mejores gestores de fondos. Pero pocos lo consiguen. El s\u00edmil, en este caso, se acercar\u00eda m\u00e1s al US Open. No en vano, <strong>Pedro Escudero<\/strong> fue jugador profesional de tenis a primeros de los 90, \u00e9poca en la que compiti\u00f3 en torneos con tenistas como Albert Costa y Carlos Moy\u00e1. Una lesi\u00f3n de codo le retir\u00f3 del deporte profesional, que cambi\u00f3 por las finanzas hasta triunfar en Wall Street.<\/p>\n          <span class=\"autoplay videoCount\">\n            <div class=\"videoC autoplay videoCount\" data-autoplay=\"false\">\n                <figure>\n                <div id=\"video_6396940585112\">\n                    <div\n                        class=\"video-player video nibara-element\"\n                        data-voc-video-player\n                        data-voc-video-player-source=\"brightcove\"\n                        data-voc-video-player-accountname=\"elcorreo\"\n                        data-voc-video-player-videoid=\"6396940585112\"\n                        data-voc-video-player-autoplay=\"false\"\n                        data-voc-video-player-muted=\"true\"\n                        data-voc-video-player-poster=\"\"\n                        data-nibara-module=\"video-player\">\n                        <!-- <div class=\"video-player-play-button\">\n                            <span class=\"boton-video\">\n                                <svg viewBox=\"0 0 24 24\">\n                                    <path d=\"M8,5.14V19.14L19,12.14L8,5.14Z\"><\/path>\n                                <\/svg>\n                            <\/span>\n                        <\/div> --> \n                    <\/div>\n                    <style>\n                    .video-player {\n                        position: relative;\n                        display: block;\n                    }\n                     \n                    .boton-video {\n                        position: absolute;\n                        top: 50%;\n                        left: 50%;\n                        width: 60px;\n                        height: 60px;                                                  \n                        z-index: 1;\n                        pointer-events:none !important;\n                    }\n                     \n                    .boton-video svg {\n                        max-width: 60px;\n                        max-height: 60px;\n                        fill: #fff\n                    }   \n                    <\/style>\n                <\/div>\n                <\/figure>\n            <\/div>\n          <\/span><p class=\"parrafocount\">Nueve a\u00f1os despu\u00e9s de fundar Doma Perpetual, uno de los \u2018hedge funds\u2019 m\u00e1s rentables del mercado estadounidense, Pedro Escudero lanza en Espa\u00f1a <a href=\"https:\/\/silverway.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Silverway Asset Management<\/a>, una gestora que pretende \u00abdemocratizar\u00bb la inversi\u00f3n en un fondo que <strong>empezar\u00e1 a funcionar en los pr\u00f3ximos d\u00edas<\/strong> con<strong> aportaciones desde 500 euros.<\/strong> El objetivo es replicar su fondo americano, donde gestiona 1.000 millones de d\u00f3lares de patrimonio con rentabilidades anuales medias del 17%, una de las mayores del mundo.<\/p>[vc_single_image image=\u00bb157645&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb][\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-10-12 tablet-col-1-1&#8243;]<p class=\"parrafocount\">Dentro de una gira para presentar este proyecto que le ha llevado a recalar en las principales ciudades \u2013ha abierto oficinas en Madrid, Barcelona y Bilbao\u2013, el \u2018Warren Buffet espa\u00f1ol\u2019, como ha sido calificado, acudi\u00f3 el pasado martes al Hotel Carlton de Bilbao, donde mantuvo una charla con la periodista Ainhoa Garc\u00eda en presencia de numeroso p\u00fablico. \u00abPedro Escudero representa una combinaci\u00f3n poco habitual de <strong>disciplina competitiva, experiencia internacional y visi\u00f3n de largo plazo.<\/strong> Porque si algo le hace especialmente interesante es la manera en la que ha construido una filosof\u00eda de inversi\u00f3n basada en la paciencia, en el an\u00e1lisis riguroso, en la selecci\u00f3n de negocios de calidad y en una idea que hoy conviene recordar: la creaci\u00f3n de riqueza no suele venir del ruido, ni de la prisa, ni de los atajos, sino del criterio, de la disciplina y del largo plazo\u00bb, subray\u00f3 la presentadora.<\/p>\n        <h2 class=\"\">Del tenis al \u00e9xito en las finanzas<\/h2>\n    <p class=\"parrafocount\">Nacido en Le\u00f3n y criado en Galicia, sus or\u00edgenes humildes no le impidieron triunfar en el deporte de la raqueta a base de tes\u00f3n, la cualidad que m\u00e1s ha impulsado su \u00e9xito empresarial. Tras recalar en Estados Unidos gracias a un amigo para tratarse de la lesi\u00f3n que arrastraba, el diag\u00f3stico le apart\u00f3 del tenis profesional. \u00abEl m\u00e9dico me sugiri\u00f3 que cambiara de carrera; ese d\u00eda fue horrible\u00bb, explic\u00f3. Lo poco que pod\u00eda jugar s\u00ed le sirvi\u00f3 para obtener una beca parcial y matricularse en la <strong>Universidad de Duke.<\/strong> \u00abMe toc\u00f3 trabajar, hacer un poco de todo para poder sobrevivir\u00bb. Este superviviente \u2013subi\u00f3 al escenario mientras sonaba la canci\u00f3n \u2018Eye of the Tiger\u2019, de Survivor\u2013 pronto se dio cuenta de que para llegar a lo m\u00e1s alto en Estados Unidos, \u00abun pa\u00eds de meritocracia pura y dura\u00bb, necesitaba rescatar el esp\u00edritu que le hab\u00eda servido para triunfar en el tenis. \u00abMe esforc\u00e9 al m\u00e1ximo hasta sacar sobresaliente en todas las asignaturas. La verdad es que yo no soy de los m\u00e1s inteligentes del mundo, no soy un genio, pero<strong> mi disciplina es m\u00e1xima<\/strong>\u00bb, valor\u00f3.<\/p>\n        <blockquote class=\"derecha \">\n\t\t<p class=\"parrafocount\">La rentabilidad anual m\u00e1xima que alcanza Escudero con su fondo estadounidense es del 17%<\/p>\n        <address><\/address>\n\t\t<\/blockquote>\n    <p class=\"parrafocount\">Tras empezar a trabajar en <strong>Lehman Brothers<\/strong>, regres\u00f3 a Duke para cursar un MBA e iniciar una carrera mete\u00f3rica que le llev\u00f3 a ocupar puestos de responsabilidad en <strong>JP Morgan.<\/strong> \u00abYo quer\u00eda ser uno de los mayores inversionistas del mundo, as\u00ed que apliqu\u00e9 el mismo sistema que conoc\u00eda de cuando jugaba al tenis, que no es otro que meter horas y horas en el estudio de empresas que resultaban interesantes para invertir\u00bb. Este aprendizaje, al que dedic\u00f3 \u2013y dedica\u2013 tiempo todos los d\u00edas de la semana, comenz\u00f3 a dar resultados. \u00abLlevaba la mitad del \u2018trading floor\u2019 (operaciones financieras) de Latinoam\u00e9rica para JP Morgan, y me di cuenta de que <strong>ganaba m\u00e1s dinero con mi cuenta personal<\/strong>, que asciende a cifras de 7 y 8 d\u00edgitos\u00bb, expuso Pedro Escudero, quien tiene su residencia en Miami.<\/p>\n        <blockquote class=\"derecha \">\n\t\t<p class=\"parrafocount\">Inter\u00e9s compuesto: \u00ab10.000 euros invertidos durante 40 a\u00f1os al 15% se convierten en 2,6 millones si eres capaz de posponer<br \/>\nla gratificaci\u00f3n\u00bb<\/p>\n        <address><\/address>\n\t\t<\/blockquote>\n    <p class=\"parrafocount\">Asegurada su salud financiera \u2013\u00abobtenerla era clave para m\u00ed; ahora esto ya es pasi\u00f3n\u00bb\u2013 se lanz\u00f3 a crear de cero un fondo que re\u00fane a algunos de los mayores inversores institucionales. Actualmente, est\u00e1 <strong>considerado como uno de los mejores inversores del mundo<\/strong>. \u00abSiempre hay a\u00f1os mejores y peores, pero el inversor institucional americano te pide que le ganes entre un 4 y un 6% al S&amp;P 500\u00bb, explic\u00f3.<\/p><p class=\"parrafocount\">Su m\u00e9todo consiste en apostar por <strong>empresas que operan en sectores en los que hay \u00fanicamente dos o tres competidores<\/strong>, lo que asegura una demanda alta incluso con subidas de precios, es decir, capacidad de mantener ventas y m\u00e1rgenes en entornos inflacionistas. \u00abAl contrario que en el tenis, cuanta m\u00e1s competici\u00f3n, peor\u00bb. Por eso, el CEO de Silverway huye del riesgo y de las promesas de dinero f\u00e1cil invirtiendo en Estados Unidos, Canad\u00e1, Europa y un poco en Jap\u00f3n y Australia. \u00abEn mercados emergentes corres peligros monetarios, pol\u00edticos y regulatorios\u00bb.<\/p>\n        <h2 class=\"\">Predictibilidad m\u00e1xima<\/h2>\n    <p class=\"parrafocount\">Con la experiencia adquirida a lo largo de 30 a\u00f1os en el mercado norteamericano, \u00abel m\u00e1s dif\u00edcil de batir del mundo\u00bb, Escudero acerca a Europa este fondo de inversi\u00f3n, que tiene <strong>registrado en Luxemburgo<\/strong> para cumplir con la legislaci\u00f3n europea. Adem\u00e1s de explorar sectores con grandes barreras de entrada para los competidores, como el del mantenimiento de aviones \u2013en el otro extremo estar\u00eda la automoci\u00f3n, donde la extrema competencia impide subir precios, o el mercado de materias primas\u2013, Silverway AM aplica el <strong>inter\u00e9s compuesto<\/strong>, al que Albert Einstein calific\u00f3 como la octava maravilla del mundo. \u00abCuando acumulas un retorno a trav\u00e9s del tiempo, es como una bola de nieve que baja por la monta\u00f1a, cada vez se hace m\u00e1s grande. Aplicado ese inter\u00e9s compuesto al dinero significa que con capitales muy peque\u00f1os puedes construir riquezas gigantescas. Traducido a cifras, si inviertes 10.000 euros por 40 a\u00f1os al 15%, son 2,6 millones de euros con los que puedes cambiar la vida a un hijo o un nieto. La clave est\u00e1 en, adem\u00e1s de disponer de ese dinero, en la capacidad de posponer la gratificaci\u00f3n y en encontrar ese 15%. <strong>Un 9% a largo plazo solo te lo da EE UU en el S&amp;P 500<\/strong>\u00bb, asegur\u00f3.<\/p>[vc_single_image image=\u00bb157653&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb][vc_empty_space]<p class=\"parrafocount\">En definitiva, Silverway acerca al peque\u00f1o inversor el pujante mercado estadounidense, aunque la idea es incorporar a su portfolio <strong>compa\u00f1\u00edas europeas<\/strong> que presentan una predictibilidad m\u00e1xima. \u00abEs la predictibilidad la que te da la certeza de que los beneficios van a seguir creciendo. Ah\u00ed es cuando ya no est\u00e1s apostando o especulando, como en la bolsa, sino invirtiendo\u00bb.<\/p><p class='parrafocount'><p class='parrafocount'>Los inversores podr\u00e1n contratar los servicios de la gestora a trav\u00e9s de su web. Escudero sostuvo que el <strong>periodo de inversi\u00f3n m\u00ednimo recomendable es de cinco a\u00f1os<\/strong>, aunque el fondo garantiza la liquidez en caso de que se necesite el dinero. La charla concluy\u00f3 con un c\u00f3ctel que se convirti\u00f3 en una sesi\u00f3n informal de \u2018networking\u2019, en el que el propio Pedro Escudero y las personas que forman el equipo de Silverway en Bilbao resolvieron dudas y aportaron m\u00e1s informaci\u00f3n a los asistentes, entre los que figuraban empresarios, aut\u00f3nomos y particulares.<\/p>\n        <h2 class=\"\">V\u00eddeo completo<\/h2>\n    \n          <span class=\"autoplay videoCount\">\n            <div class=\"videoC autoplay videoCount\" data-autoplay=\"false\">\n                <figure>\n                <div id=\"video_6396934829112\">\n                    <div\n                        class=\"video-player video nibara-element\"\n                        data-voc-video-player\n                        data-voc-video-player-source=\"brightcove\"\n                        data-voc-video-player-accountname=\"elcorreo\"\n                        data-voc-video-player-videoid=\"6396934829112\"\n                        data-voc-video-player-autoplay=\"false\"\n                        data-voc-video-player-muted=\"true\"\n                        data-voc-video-player-poster=\"\"\n                        data-nibara-module=\"video-player\">\n                        <!-- <div class=\"video-player-play-button\">\n                            <span class=\"boton-video\">\n                                <svg viewBox=\"0 0 24 24\">\n                                    <path d=\"M8,5.14V19.14L19,12.14L8,5.14Z\"><\/path>\n                                <\/svg>\n                            <\/span>\n                        <\/div> --> \n                    <\/div>\n                    <style>\n                    .video-player {\n                        position: relative;\n                        display: block;\n                    }\n                     \n                    .boton-video {\n                        position: absolute;\n                        top: 50%;\n                        left: 50%;\n                        width: 60px;\n                        height: 60px;                                                  \n                        z-index: 1;\n                        pointer-events:none !important;\n                    }\n                     \n                    .boton-video svg {\n                        max-width: 60px;\n                        max-height: 60px;\n                        fill: #fff\n                    }   \n                    <\/style>\n                <\/div>\n                <\/figure>\n            <\/div>\n          <\/span>[\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-10-12 tablet-col-1-1 recuadro\u00bb]<p class=\"parrafocount\"><strong>EL TRIPLE RIESGO DE LA RENTA FIJA<\/strong><\/p><p class='parrafocount'><p class='parrafocount'>La filosof\u00eda inversora de Pedro Escudera choca de frente con ese perfil de ahorrador que tiene aversi\u00f3n al riesgo. Parad\u00f3jicamente, se\u00f1al\u00f3 que la renta fija \u00abtiene un triple peligro: el del deudor, que puede ser un pa\u00eds o una empresa, el de la tasa de inter\u00e9s y el que ni siquiera compensa la inflaci\u00f3n\u00bb, repas\u00f3. En su opini\u00f3n, estos fondos solo tienen sentido si se est\u00e1 invertido a muy corto plazo y como compensaci\u00f3n a un inter\u00e9s muy bajo se garantiza la liquidez. \u00abYo tengo m\u00e1s del 90% de todos mis activos en renta variable, que es la \u00fanica que te da un inter\u00e9s compuesto que supera a todos los activos\u00bb, a\u00f1adi\u00f3.<\/p>[\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column]\n        <div class='bloque'>\n         <div class='compartir'><p>Compartir<\/p><ul>\n                <li class='facebook'>\n                            <a href='https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/elcorreo.com\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/' class='bcl-compartir-fb' target='_blank' title='Compartelo en Facebook' rel='nofollow'>\n                        <i class='facebook'><\/i>\n                    <\/a>\n                <\/li><li class='twitter'>\n                    <a href='https:\/\/twitter.com\/intent\/tweet?text=https:\/\/elcorreo.com\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/' class='bcl-compartir-tw twitter' target='_blank' title='Compartelo en Twitter' rel='nofollow'>\n                        <i class='twitter'><\/i>\n                    <\/a>\n                <\/li><li class='whatsapp'>\n                    <a href='whatsapp:\/\/send?text=https:\/\/elcorreo.com\/content-local\/la-inversion-mas-sofisticada-en-wall-street-al-alcance-del-pequeno-ahorrador\/' class='whatsapp' target='_blank' title='Compartelo en whatsapp' rel='nofollow'>\n                        <i class='whatsapp'><\/i>\n                    <\/a>\n                <\/li>\n                   <\/ul><\/div>\n        <div class='pie-ad '>\n            <p><strong>Content Service<\/strong> elaborado por <a href=\"https:\/\/www.srbediciones.com\/\" target=\"_blank\" rel=\"noopener\">SRB Ediciones<\/a><\/p>\n        <\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-1-1 tablet-col-1-1&#8243;][\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-10-12 tablet-col-1-1&#8243;][vc_single_image image=\u00bb157645&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb][\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-10-12 tablet-col-1-1&#8243;][vc_single_image image=\u00bb157653&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb][vc_empty_space][\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column el_class=\u00bbcol-10-12 tablet-col-1-1 recuadro\u00bb][\/vc_column][\/vc_row][vc_row centrar=\u00bbtrue\u00bb el_class=\u00bbgrid grid-pad\u00bb][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[43],"tags":[827,491,2257,727,3681],"acf":[],"_links":{"self":[{"href":"\/content-local\/wp-json\/wp\/v2\/posts\/157641"}],"collection":[{"href":"\/content-local\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/content-local\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/content-local\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"\/content-local\/wp-json\/wp\/v2\/comments?post=157641"}],"version-history":[{"count":16,"href":"\/content-local\/wp-json\/wp\/v2\/posts\/157641\/revisions"}],"predecessor-version":[{"id":157670,"href":"\/content-local\/wp-json\/wp\/v2\/posts\/157641\/revisions\/157670"}],"wp:attachment":[{"href":"\/content-local\/wp-json\/wp\/v2\/media?parent=157641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/content-local\/wp-json\/wp\/v2\/categories?post=157641"},{"taxonomy":"post_tag","embeddable":true,"href":"\/content-local\/wp-json\/wp\/v2\/tags?post=157641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}